{"id":11689,"date":"2023-06-14T14:55:24","date_gmt":"2023-06-14T14:55:24","guid":{"rendered":"https:\/\/jazzar-consult.com\/%d8%a7%d9%84%d9%85%d8%af%d9%86-%d8%a7%d9%84%d8%b0%d9%83%d9%8a%d8%a9\/"},"modified":"2025-02-11T12:28:04","modified_gmt":"2025-02-11T12:28:04","slug":"%d8%a7%d9%84%d9%85%d8%af%d9%86-%d8%a7%d9%84%d8%b0%d9%83%d9%8a%d8%a9","status":"publish","type":"page","link":"https:\/\/jazzar-consult.com\/ar\/%d8%a7%d9%84%d9%85%d8%af%d9%86-%d8%a7%d9%84%d8%b0%d9%83%d9%8a%d8%a9\/","title":{"rendered":"\u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11689\" class=\"elementor elementor-11689 elementor-11424\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f8c60c9 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f8c60c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"lqd-css-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9bdb217\" style=\"--lqd-sticky-offset:30px\" data-id=\"9bdb217\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b862f8d elementor-widget elementor-widget-wpb-accordion-menu-or-category-pro\" data-id=\"b862f8d\" data-element_type=\"widget\" data-widget_type=\"wpb-accordion-menu-or-category-pro.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpb-wamc-elementor-widget wpb-wamc-elementor-widget-show-in-popup\">\t\t\t<div class=\"wpb_category_n_menu_accordion wpb_accordion_free_version wpb_wmca_accordion_wrapper_theme_transparent wpb_the_menu_accordion\" data-shortcode_id=\"12840\" data-accordion=\"true\" data-indicator_icon=\"+\">\n\t\t\t\t\t\t\t\t<ul id=\"menu-services\" class=\"wpb_category_n_menu_accordion_list\"><li id=\"menu-item-13853\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13853\"><a href=\"https:\/\/jazzar-consult.com\/engineering-consulting\/\">\u0627\u0633\u062a\u0634\u0627\u0631\u0627\u062a \u0647\u0646\u062f\u0633\u064a\u0629<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-12970\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12970\"><a href=\"https:\/\/jazzar-consult.com\/design\/\">\u062a\u0635\u0645\u064a\u0645<\/a><\/li>\n\t<li id=\"menu-item-12969\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12969\"><a href=\"https:\/\/jazzar-consult.com\/supervision\/\">\u0627\u0644\u0625\u0634\u0631\u0627\u0641<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-13876\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13876\"><a href=\"https:\/\/jazzar-consult.com\/hydrology\/\">\u0639\u0644\u0645 \u0627\u0644\u0645\u064a\u0627\u0647<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-13880\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13880\"><a href=\"https:\/\/jazzar-consult.com\/urban-hydrology\/\">\u0647\u064a\u062f\u0631\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u0645\u0646\u0627\u0637\u0642 \u0627\u0644\u062d\u0636\u0631\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-13881\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13881\"><a href=\"https:\/\/jazzar-consult.com\/surface-water-modeling\/\">\u0646\u0645\u0630\u062c\u0629 \u0633\u0631\u064a\u0627\u0646 \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u0633\u0637\u062d\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-13882\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13882\"><a href=\"https:\/\/jazzar-consult.com\/erosion-and-sediment-control\/\">\u2022\u0627\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u062a\u0622\u0643\u0644 \u0648\u062a\u0631\u0633\u064a\u0628 \u0627\u0644\u062a\u0631\u0628\u0629<\/a><\/li>\n\t<li id=\"menu-item-13883\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13883\"><a href=\"https:\/\/jazzar-consult.com\/flood-defense-design\/\">\u0648\u0633\u0627\u0626\u0644 \u062f\u0631\u0621 \u0627\u0644\u0633\u064a\u0648\u0644<\/a><\/li>\n\t<li id=\"menu-item-14344\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14344\"><a href=\"https:\/\/jazzar-consult.com\/urban-solutions\/\">\u0627\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u0645\u064a\u0627\u0647 \u0627\u0644\u0623\u0645\u0637\u0627\u0631<\/a><\/li>\n\t<li id=\"menu-item-14346\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14346\"><a href=\"https:\/\/jazzar-consult.com\/flood-risk-assessment\/\">\u0627\u0644\u0645\u0646\u0627\u0637\u0642 \u0627\u0644\u0645\u0639\u0631\u0651\u0636\u0629 \u0644\u0644\u0641\u064a\u0636\u0627\u0646\u0627\u062a<\/a><\/li>\n\t<li id=\"menu-item-14345\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14345\"><a href=\"https:\/\/jazzar-consult.com\/flood-protection-design\/\">\u062f\u0631\u0621 \u0627\u062e\u0637\u0627\u0631 \u0627\u0644\u0633\u064a\u0648\u0644<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-13900\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13900\"><a href=\"https:\/\/jazzar-consult.com\/smart-scan\/\">\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u0630\u0643\u064a<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-13897\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13897\"><a href=\"https:\/\/jazzar-consult.com\/surveying\/\">\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u0647\u0646\u062f\u0633\u064a<\/a><\/li>\n\t<li id=\"menu-item-13896\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13896\"><a href=\"https:\/\/jazzar-consult.com\/scanning\/\">\u0627\u0644\u0645\u0633\u062d<\/a><\/li>\n\t<li id=\"menu-item-13898\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13898\"><a href=\"https:\/\/jazzar-consult.com\/drone\/\">\u0637\u0627\u0626\u0631\u0629 \u0628\u062f\u0648\u0646 \u0637\u064a\u0627\u0631<\/a><\/li>\n\t<li id=\"menu-item-14520\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14520\"><a href=\"https:\/\/jazzar-consult.com\/mobile-mapping-surveying\/\">\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u0623\u0631\u0636\u064a \u0648\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u0630\u0643\u064a<\/a>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-14511\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14511\"><a href=\"https:\/\/jazzar-consult.com\/data-processing-deliverables-reporting\/\">\u062f\u0631\u0627\u0633\u0640\u0629 \u0647\u064a\u0640\u062f\u0631\u0648\u0644\u0648\u062c\u064a\u0640\u0640\u0629 \u0644\u0623\u0631\u0636 \u0645\u0648\u0642\u0639 \u0627\u0644\u062e\u0632\u0627\u0646 \u0627\u0644\u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a \u0628\u062d\u064a \u0627\u0644\u062c\u0627\u0645\u0639\u0629 \u2013 \u0627\u0644\u0638\u0647\u0631\u0627\u0646 \u2013 \u0627\u0644\u062f\u0645\u0627\u0645.<\/a><\/li>\n\t\t<li id=\"menu-item-14512\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14512\"><a href=\"https:\/\/jazzar-consult.com\/hydrographic-marine-surveys-when-applicable\/\">\u0627\u0644\u0645\u0633\u0648\u062d\u0627\u062a \u0627\u0644\u0647\u064a\u062f\u0631\u0648\u063a\u0631\u0627\u0641\u064a\u0629 \u0648\u0627\u0644\u0628\u062d\u0631\u064a\u0629<\/a><\/li>\n\t\t<li id=\"menu-item-14513\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14513\"><a href=\"https:\/\/jazzar-consult.com\/3d-laser-scanning-smart-surveying\/\">\u0627\u0644\u0645\u0633\u062d \u0628\u0627\u0644\u0644\u064a\u0632\u0631 \u0627\u0644\u062b\u0644\u0627\u062b\u064a \u0627\u0644\u0623\u0628\u0639\u0627\u062f \u0648\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u0630\u0643\u064a<\/a><\/li>\n\t\t<li id=\"menu-item-14514\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14514\"><a href=\"https:\/\/jazzar-consult.com\/aerial-drone-based-surveys\/\">\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u062c\u0648\u064a \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0637\u0627\u0626\u0631\u0627\u062a \u0628\u062f\u0648\u0646 \u0637\u064a\u0627\u0631<\/a><\/li>\n\t\t<li id=\"menu-item-14515\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14515\"><a href=\"https:\/\/jazzar-consult.com\/corridor-transportation-surveys\/\">\u0645\u0633\u0648\u062d\u0627\u062a \u0627\u0644\u0637\u0631\u0642 \u0648\u0627\u0644\u0645\u0645\u0631\u0627\u062a<\/a><\/li>\n\t\t<li id=\"menu-item-14516\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14516\"><a href=\"https:\/\/jazzar-consult.com\/utility-infrastructure-surveys\/\">\u0645\u0633\u0648\u062d\u0627\u062a \u0627\u0644\u0645\u0631\u0627\u0641\u0642 \u0648\u0627\u0644\u0628\u0646\u064a\u0629 \u0627\u0644\u062a\u062d\u062a\u064a\u0629<\/a><\/li>\n\t\t<li id=\"menu-item-14517\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14517\"><a href=\"https:\/\/jazzar-consult.com\/engineering-construction-surveys\/\">\u0627\u0644\u0645\u0633\u0648\u062d\u0627\u062a \u0627\u0644\u0647\u0646\u062f\u0633\u064a\u0629 \u0648\u0627\u0644\u0625\u0646\u0634\u0627\u0626\u064a\u0629<\/a><\/li>\n\t\t<li id=\"menu-item-14518\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14518\"><a href=\"https:\/\/jazzar-consult.com\/topographic-cadastral-surveys\/\">\u0627\u0644\u0631\u0641\u0639 \u0627\u0644\u0637\u0628\u0648\u063a\u0631\u0627\u0641\u064a \u0648\u0627\u0644\u062d\u062f\u0648\u062f\u064a<\/a><\/li>\n\t\t<li id=\"menu-item-14519\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14519\"><a href=\"https:\/\/jazzar-consult.com\/control-geodetic-networks\/\">\u0634\u0628\u0643\u0627\u062a \u0627\u0644\u062a\u062d\u0643\u0645 \u0648\u0627\u0644\u062c\u064a\u0648\u062f\u064a\u0633\u064a\u0627<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-13878\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13878\"><a href=\"https:\/\/jazzar-consult.com\/gis\/\">\u0646\u0638\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u062c\u063a\u0631\u0627\u0641\u064a\u0629<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-13884\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13884\"><a href=\"https:\/\/jazzar-consult.com\/geo-bim\/\">\u0646\u0638\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u062c\u063a\u0631\u0627\u0641\u064a\u0629 \u0648 \u0646\u0645\u0630\u062c\u0629 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0628\u0646\u0627\u0621<\/a><\/li>\n\t<li id=\"menu-item-13886\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13886\"><a href=\"https:\/\/jazzar-consult.com\/remote-sensing\/\">\u0627\u0644\u0627\u0633\u062a\u0634\u0639\u0627\u0631 \u0639\u0646 \u0628\u0639\u062f<\/a><\/li>\n\t<li id=\"menu-item-13885\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13885\"><a href=\"https:\/\/jazzar-consult.com\/create-geographical-databases\/\">\u0642\u0648\u0627\u0639\u062f \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062c\u063a\u0631\u0627\u0641\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-14438\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14438\"><a href=\"https:\/\/jazzar-consult.com\/interactive-maps\/\">\u0627\u0644\u062e\u0631\u0627\u0626\u0637 \u0627\u0644\u062a\u0641\u0627\u0639\u0644\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-14437\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14437\"><a href=\"https:\/\/jazzar-consult.com\/story-map\/\">\u0627\u0644\u062e\u0631\u0627\u0626\u0637 \u0627\u0644\u0642\u0635\u0635\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-14436\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14436\"><a href=\"https:\/\/jazzar-consult.com\/geo-ai\/\">\u0627\u0644\u0630\u0643\u0627\u0621 \u0627\u0644\u0627\u0635\u0637\u0646\u0627\u0639\u064a \u0627\u0644\u062c\u064a\u0648\u0645\u0643\u0627\u0646\u064a<\/a><\/li>\n\t<li id=\"menu-item-14435\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14435\"><a href=\"https:\/\/jazzar-consult.com\/geo-bim-2\/\">\u062a\u0643\u0627\u0645\u0644 \u0646\u0638\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u062c\u063a\u0631\u0627\u0641\u064a\u0629 \u0645\u0639 \u0646\u0645\u0630\u062c\u0629 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0628\u0646\u0627\u0621<\/a><\/li>\n\t<li id=\"menu-item-14434\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14434\"><a href=\"https:\/\/jazzar-consult.com\/in-doors\/\">\u0627\u0644\u062d\u0644\u0648\u0644 \u0627\u0644\u062f\u0627\u062e\u0644\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-14433\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14433\"><a href=\"https:\/\/jazzar-consult.com\/smart-cities-solutions\/\">\u062d\u0644\u0648\u0644 \u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-14432\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14432\"><a href=\"https:\/\/jazzar-consult.com\/digital-twins\/\">\u0627\u0644\u062a\u0648\u0623\u0645\u0629 \u0627\u0644\u0631\u0642\u0645\u064a\u0629<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-13877\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13877\"><a href=\"https:\/\/jazzar-consult.com\/geophysics\/\">\u0627\u0644\u062c\u064a\u0648\u0641\u064a\u0632\u064a\u0627\u0621<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-13887\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13887\"><a href=\"https:\/\/jazzar-consult.com\/electromagnetic-terrain-conductivity-tem\/\">\u0648\u062d\u062f\u0629 \u062a\u0642\u064a\u064a\u0645 \u0647\u0646\u062f\u0633\u064a \u0644\u0644\u0645\u0646\u0634\u0623\u062a \u0648 \u0627\u0644\u0628\u064a\u0646\u064a\u0629 \u0627\u0644\u062a\u062d\u062a\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-13888\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13888\"><a href=\"https:\/\/jazzar-consult.com\/magnetic-survey\/\">\u0648\u062d\u062f\u0629 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u0623\u0628\u0627\u0631 \u0627\u0644\u0645\u064a\u0627\u0629 \u0627\u0644\u062c\u0648\u0641\u064a\u0629<\/a><\/li>\n\t<li id=\"menu-item-13889\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13889\"><a href=\"https:\/\/jazzar-consult.com\/borehole-geophysical-and-video-logging\/\">\u0627\u0644\u0645\u0633\u062d \u0627\u0644\u062c\u064a\u0648\u0641\u064a\u0632\u064a\u0627\u0626\u064a \u0644\u0644\u0622\u0628\u0627\u0631 \u0648\u062a\u0633\u062c\u064a\u0644 \u0627\u0644\u0641\u064a\u062f\u064a\u0648<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-13942\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13942\"><a href=\"https:\/\/jazzar-consult.com\/programing\/\">\u0627\u0644\u0628\u0631\u0645\u062c\u0647<\/a><\/li>\n<li id=\"menu-item-13941\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13941\"><a href=\"https:\/\/jazzar-consult.com\/building-information-modeling\/\">\u0646\u0645\u0630\u062c\u0629 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0628\u0646\u0627\u0621<\/a><\/li>\n<li id=\"menu-item-13940\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13940\"><a href=\"https:\/\/jazzar-consult.com\/environmental\/\">\u0628\u064a\u0626\u064a<\/a><\/li>\n<li id=\"menu-item-13939\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13939\"><a href=\"https:\/\/jazzar-consult.com\/ai-smart-cites\/\">\u0627\u0644\u0630\u0643\u0627\u0621 \u0627\u0644\u0627\u0635\u0637\u0646\u0627\u0639\u064a \u0648\u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5945d37c\" data-id=\"5945d37c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b06aaec elementor-widget elementor-widget-ld_content_box\" data-id=\"2b06aaec\" data-element_type=\"widget\" data-widget_type=\"ld_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"lqd-fb pos-rel lqd-fb-style-1 lqd-fb-style-1-3 lqd-fb-content-overlay lqd-fb-zoom-img-onhover border-radius-4 overflow-hidden h-pt-60\" data-inview=\"true\">\n\t\t\t\t\t<div class=\"lqd-fb-inner lqd-overlay\">\n\n\t\t\t\t<div class=\"overflow-hidden lqd-fb-img lqd-overlay\">\n\n\t\t\t\t\t<figure class=\"w-100 h-100\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"w-100 h-100 objfit-cover objpos-center\" src=\"https:\/\/jazzar-consult.com\/wp-content\/uploads\/2023\/06\/Smart-Cities.webp\">\t\t\t\t\t<\/figure>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content lqd-overlay d-flex align-items-end\">\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-content-inner d-flex flex-column justify-content-between pos-rel h-100 w-100 p-4\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"lqd-fb-content-top\">\n\t\t\t\t\t\t\t<h6 class=\"mt-0 mb-0\">\u0642\u0633\u0645<\/h6>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"lqd-fb-content-bottom\">\n\n\t\t\t\t\t\t\t<h2 class=\"lqd-fb__title mt-0 mb-2 \">\u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629 <\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"mt-0 mb-3\">\u0645\u0646 \u062e\u0644\u0627\u0644 \u0645\u0632\u064a\u062c \u0641\u0631\u064a\u062f \u0645\u0646 \u062a\u062e\u0635\u0635\u0627\u062a \u0648\u062e\u0628\u0631\u0627\u062a \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0628\u0646\u0627\u0621 \u0648\u0627\u0644\u062a\u0635\u0645\u064a\u0645.<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76d7e2de elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"76d7e2de\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97cdc7b1ca8\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > \u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629 <\/h3>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-523ee885 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"523ee885\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97cdc7b2c69\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > \u062a\u0634\u0645\u0644 \u062e\u062f\u0645\u0627\u062a \u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629 \u0645\u062c\u0645\u0648\u0639\u0629 \u0648\u0627\u0633\u0639\u0629 \u0645\u0646 \u0627\u0644\u062d\u0644\u0648\u0644 \u0648\u0627\u0644\u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a\u0627\u062a \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0647\u062f\u0641 \u0625\u0644\u0649 \u062a\u062d\u0633\u064a\u0646 \u0646\u0648\u0639\u064a\u0629 \u0627\u0644\u062d\u064a\u0627\u0629 \u0648\u0627\u0644\u0627\u0633\u062a\u062f\u0627\u0645\u0629 \u0648\u0643\u0641\u0627\u0621\u0629 \u0627\u0644\u0628\u064a\u0626\u0627\u062a \u0627\u0644\u062d\u0636\u0631\u064a\u0629. \u0641\u064a \u062d\u064a\u0646 \u0623\u0646 \u0631\u0633\u0645 \u0627\u0644\u062e\u0631\u0627\u0626\u0637 \u0639\u0644\u0649 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\u0629 \u0647\u0648 \u0645\u062c\u0631\u062f \u062c\u0627\u0646\u0628 \u0648\u0627\u062d\u062f \u0645\u0646 \u062c\u0648\u0627\u0646\u0628 \u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629 \u060c \u0625\u0644\u0627 \u0623\u0646\u0647 \u064a\u0644\u0639\u0628 \u062f\u0648\u0631\u064b\u0627 \u0645\u0647\u0645\u064b\u0627 \u0641\u064a \u062c\u0645\u0639 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0648\u0645\u0631\u0627\u0642\u0628\u062a\u0647\u0627 \u0648\u062a\u062d\u0644\u064a\u0644\u0647\u0627. \u0641\u064a\u0645\u0627 \u064a\u0644\u064a \u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0644\u0649 \u062e\u062f\u0645\u0627\u062a \u0627\u0644\u0645\u062f\u0646 \u0627\u0644\u0630\u0643\u064a\u0629 \u0648\u0643\u064a\u0641 \u062a\u0633\u0627\u0647\u0645 \u062e\u0631\u0627\u0626\u0637 \u0627\u0644\u062c\u0648\u0627\u0644 \u0641\u064a\u0647\u0627:<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7894b4d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7894b4d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/jazzar-consult.com\/wp-content\/uploads\/elementor\/css\/custom-widget-icon-list.min.css?ver=1764493380\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0648\u0627\u0644\u062a\u0637\u0648\u064a\u0631 \u0627\u0644\u0639\u0645\u0631\u0627\u0646\u064a.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0627\u0644\u0646\u0642\u0644 \u0648\u0627\u0644\u062a\u0646\u0642\u0644.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0627\u0644\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u0628\u064a\u0626\u064a\u0629.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0637\u0627\u0642\u0629.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0627\u0644\u0623\u0645\u0646 \u0648\u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u0639\u0627\u0645\u0629.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> \u0645\u0634\u0627\u0631\u0643\u0629 \u0627\u0644\u0645\u0648\u0627\u0637\u0646\u064a\u0646 \u0648\u0627\u0644\u062e\u062f\u0645\u0627\u062a.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46371710 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"46371710\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-546e1aba elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"546e1aba\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97cdc7b65c7\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > \u0645\u0632\u0627\u064a\u0627 \u0627\u0644\u062e\u062f\u0645\u0629<\/h3>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e174521 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e174521\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-288d7c33\" data-id=\"288d7c33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce66a4d elementor-widget elementor-widget-video\" data-id=\"4ce66a4d\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XHOmBV4js_E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Engineering Design Supervision Hydrology Urban Hydrology Surface Water Modeling Erosion and Sediment Control Rainfall Runoff Modeling Flood Defense Design GIS &#038; Geo AI Geo BIM Remote Sensing Geographical Databases Smart Survey Drone Mobile Mapping Scanning Land Survey Geophysics (GPR) Electrical Resistivity Tomography (ERT), Soundings, and Profiling Electromagnetic Terrain Conductivity (TEM) Very Low Frequency (VLF) Profiling [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11689","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/pages\/11689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/comments?post=11689"}],"version-history":[{"count":3,"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/pages\/11689\/revisions"}],"predecessor-version":[{"id":13649,"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/pages\/11689\/revisions\/13649"}],"wp:attachment":[{"href":"https:\/\/jazzar-consult.com\/ar\/wp-json\/wp\/v2\/media?parent=11689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}